{"id":1763,"date":"2024-02-01T12:59:47","date_gmt":"2024-02-01T17:59:47","guid":{"rendered":"http:\/\/fnmhf-2025.local\/story\/success-story-heiltsuk-nation-2\/"},"modified":"2025-09-24T16:03:08","modified_gmt":"2025-09-24T20:03:08","slug":"success-story-heiltsuk-nation-2","status":"publish","type":"story","link":"https:\/\/www.fnmhf.ca\/fr\/story\/success-story-heiltsuk-nation-2\/","title":{"rendered":"Nation Heiltsuk"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1763\" class=\"elementor elementor-1763 elementor-1752\" data-elementor-post-type=\"story\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0cc7ff e-con-full e-flex e-con e-parent\" data-id=\"a0cc7ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-baf25c8 e-con-full e-flex e-con e-child\" data-id=\"baf25c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8cdb98 elementor-widget elementor-widget-text-editor\" data-id=\"d8cdb98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ha\u00edtc\u00edstut est une expression Heiltsuk qui signifie \u00ab renverser la vapeur et redresser la situation \u00bb.<\/p>\n<p>Fond\u00e9s sur le concept du potlatch Heiltsuk, la Nation Heiltsuk et les gouvernements f\u00e9d\u00e9ral et provinciaux ont entam\u00e9 le processus de r\u00e9conciliation Ha\u00edtc\u00edstut afin de n\u00e9gocier une nouvelle relation de gouvernement\u00a0 \u00e0 gouvernement. Ce processus est ax\u00e9 sur le bien-\u00eatre social dans les domaines suivants :<\/p>\n<p><\/p>\n<ul>\n<li>Infrastructure et logement<\/li>\n\n<li>Emploi, formation et d\u00e9veloppement \u00e9conomique<\/li>\n\n<li>\u00c9ducation<\/li>\n\n<li>Sant\u00e9 et bien-\u00eatre<\/li>\n\n<li>Terres et environnement<\/li>\n\n<li>Autonomie gouvernementale<\/li>\n<\/ul>\n<p><\/p>\n<p>Nich\u00e9e sur la c\u00f4te centrale de la Colombie-Britannique, la r\u00e9serve Bella Bella abrite la Nation Heiltsuk. Au cours des 20 derni\u00e8res ann\u00e9es, la population Heiltsuk, qui compte plus de 2 400 membres, a augment\u00e9 de fa\u00e7on constante, mais la population de Bella Bella est demeur\u00e9e relativement stable en raison du manque de logements disponibles. L\u2019\u00e9conomie locale est en croissance et de nombreux membres de la Nation Heiltsuk qui vivent \u00e0 l\u2019ext\u00e9rieur du village aimeraient y revenir. La collectivit\u00e9 est aux prises avec les probl\u00e8mes simultan\u00e9s du manque de logements et de d\u00e9gradation pr\u00e9matur\u00e9e du parc immobilier.<\/p>\n<p><\/p>\n<p>Le processus de r\u00e9conciliation a \u00e9t\u00e9 per\u00e7u comme une occasion de regarder au-del\u00e0 de la port\u00e9e g\u00e9n\u00e9rale du mode de production de logements de SAC. Le Conseil tribal Heiltsuk a communiqu\u00e9 avec l\u2019Indigenous Research Support Initiative (IRSI) pour favoriser une collaboration de recherche sur le logement avec l\u2019Universit\u00e9 de la Colombie-Britannique (UBC) et obtenir une l\u2019aide n\u00e9cessaire pour trouver des partenaires de mise en oeuvre qui r\u00e9pondent aux besoins de conception et de construction de la Nation. L\u2019\u00e9quipe de recherche de l\u2019Universit\u00e9 de la Colombie-Britannique a commenc\u00e9 par une phase de conception \u00e0 laquelle laNation Heiltsuk a particip\u00e9. La consultation de la collectivit\u00e9 a permis de d\u00e9terminer des options de logement adapt\u00e9es \u00e0 la culture.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7d37d6 e-con-full e-flex e-con e-child\" data-id=\"d7d37d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a29a475 elementor-widget elementor-widget-image\" data-id=\"a29a475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"317\" src=\"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2024\/03\/Heiltsuk-Qatuwas-Brown-1024x406.jpg\" class=\"attachment-large size-large wp-image-1341\" alt=\"\" srcset=\"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2024\/03\/Heiltsuk-Qatuwas-Brown-1024x406.jpg 1024w, https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2024\/03\/Heiltsuk-Qatuwas-Brown-1024x406-300x119.jpg 300w, https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2024\/03\/Heiltsuk-Qatuwas-Brown-1024x406-768x305.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-610cca2 e-con-full e-flex e-con e-child\" data-id=\"610cca2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a55d35 elementor-widget elementor-widget-text-editor\" data-id=\"6a55d35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dans un premier temps, la collectivit\u00e9 a choisi d\u2019aller de l\u2019avant avec un projet de \u00ab petite maison \u00bb pouvant assurer une vie autonome aux a\u00een\u00e9s, \u00e0 d\u2019autres personnes, aux couples et m\u00eame aux jeunes familles. Avec l\u2019aide de l\u2019IRSI, la Nation Heiltsuk a \u00e9tabli des partenariats de mise en oeuvre avec les entreprises FPInnovations et Builders without Borders.<\/p>\n<p><\/p>\n<p>La Nation a offert en vente quatre petites maisons (environ 384 pieds carr\u00e9s) dans le cadre d\u2019un processus de demande par loterie qui a eu lieu entre ao\u00fbt et septembre 2021. Le co\u00fbt de construction de chaque petite maison s\u2019\u00e9levait \u00e0 125 000 $. \u00c0 chaque petite maison a \u00e9t\u00e9 appliqu\u00e9e une subvention pour maison neuve de 55 000 $, pour un prix de vente de 70 000 $. Les participants \u00e0 la loterie devaient avoir les moyens financiers n\u00e9cessaires \u00e0 l\u2019achat direct d\u2019une petite maison, ainsi qu\u2019une lettre de confirmation de leur banque, si leur demande \u00e9tait tir\u00e9e au sort.<\/p>\n<p><\/p>\n<p>La Nation Heiltsuk a r\u00e9ussi le lancement de son programme d\u2019acc\u00e8s \u00e0 la propri\u00e9t\u00e9 gr\u00e2ce \u00e0 la garantie du Fonds pour les quatre pr\u00eats pour les petites maisons. Les prochaines phases de ce projet porteront sur la conception de maisons pour les grandes familles au moyen du processus d\u2019engagement communautaire \u00e9tabli.<\/p>\n<p><strong><em>F\u00e9licitations aux nouveaux propri\u00e9taires!<\/em><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ha\u00edtc\u00edstut est une expression Heiltsuk qui signifie \u00ab renverser la vapeur et redresser la situation \u00bb. Fond\u00e9s sur le concept du potlatch Heiltsuk, la Nation Heiltsuk et les gouvernements f\u00e9d\u00e9ral et provinciaux ont entam\u00e9 le processus de r\u00e9conciliation Ha\u00edtc\u00edstut afin de n\u00e9gocier une nouvelle relation de gouvernement  \u00e0 gouvernement.<\/p>\n","protected":false},"featured_media":852,"template":"","meta":{"_acf_changed":false},"class_list":["post-1763","story","type-story","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nation Heiltsuk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nation Heiltsuk\" \/>\n<meta property=\"og:description\" content=\"Ha\u00edtc\u00edstut est une expression Heiltsuk qui signifie \u00ab renverser la vapeur et redresser la situation \u00bb. Fond\u00e9s sur le concept du potlatch Heiltsuk, la Nation Heiltsuk et les gouvernements f\u00e9d\u00e9ral et provinciaux ont entam\u00e9 le processus de r\u00e9conciliation Ha\u00edtc\u00edstut afin de n\u00e9gocier une nouvelle relation de gouvernement \u00e0 gouvernement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/\" \/>\n<meta property=\"og:site_name\" content=\"Fonds pour les habitations du march\u00e9 des Premi\u00e8res Nations\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T20:03:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2025\/08\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"564\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/\",\"url\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/\",\"name\":\"Nation Heiltsuk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fnmhf.ca\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg\",\"datePublished\":\"2024-02-01T17:59:47+00:00\",\"dateModified\":\"2025-09-24T20:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fnmhf.ca\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fnmhf.ca\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg\",\"width\":564,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/success-story-heiltsuk-nation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fnmhf.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stories\",\"item\":\"https:\\\/\\\/www.fnmhf.ca\\\/story\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nation Heiltsuk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fnmhf.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.fnmhf.ca\\\/\",\"name\":\"Fonds pour les habitations du march\u00e9 des Premi\u00e8res Nations\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fnmhf.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nation Heiltsuk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/","og_locale":"fr_FR","og_type":"article","og_title":"Nation Heiltsuk","og_description":"Ha\u00edtc\u00edstut est une expression Heiltsuk qui signifie \u00ab renverser la vapeur et redresser la situation \u00bb. Fond\u00e9s sur le concept du potlatch Heiltsuk, la Nation Heiltsuk et les gouvernements f\u00e9d\u00e9ral et provinciaux ont entam\u00e9 le processus de r\u00e9conciliation Ha\u00edtc\u00edstut afin de n\u00e9gocier une nouvelle relation de gouvernement \u00e0 gouvernement.","og_url":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/","og_site_name":"Fonds pour les habitations du march\u00e9 des Premi\u00e8res Nations","article_modified_time":"2025-09-24T20:03:08+00:00","og_image":[{"width":564,"height":422,"url":"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2025\/08\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/","url":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/","name":"Nation Heiltsuk","isPartOf":{"@id":"https:\/\/www.fnmhf.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/#primaryimage"},"image":{"@id":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2025\/08\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg","datePublished":"2024-02-01T17:59:47+00:00","dateModified":"2025-09-24T20:03:08+00:00","breadcrumb":{"@id":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/#primaryimage","url":"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2025\/08\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg","contentUrl":"https:\/\/www.fnmhf.ca\/wp-content\/uploads\/2025\/08\/Qatuwas-Brown-her-mother-and-nieces-checking-out-her-new-house.jpg","width":564,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/www.fnmhf.ca\/story\/success-story-heiltsuk-nation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fnmhf.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Stories","item":"https:\/\/www.fnmhf.ca\/story\/"},{"@type":"ListItem","position":3,"name":"Nation Heiltsuk"}]},{"@type":"WebSite","@id":"https:\/\/www.fnmhf.ca\/#website","url":"https:\/\/www.fnmhf.ca\/","name":"Fonds pour les habitations du march\u00e9 des Premi\u00e8res Nations","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fnmhf.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/story\/1763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/types\/story"}],"version-history":[{"count":5,"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/story\/1763\/revisions"}],"predecessor-version":[{"id":12337,"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/story\/1763\/revisions\/12337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/media\/852"}],"wp:attachment":[{"href":"https:\/\/www.fnmhf.ca\/fr\/wp-json\/wp\/v2\/media?parent=1763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}